{"id":1177319,"date":"2017-10-19T15:52:09","date_gmt":"2017-10-19T19:52:09","guid":{"rendered":""},"modified":"2018-07-30T12:50:49","modified_gmt":"2018-07-30T12:50:49","slug":"3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses","status":"publish","type":"steps","link":"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/","title":{"rendered":"3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses"},"content":{"rendered":"<p>Parlez-en \u00e0 vos coll\u00e8gues. Si votre employeur ne vous donne pas de pauses, il n\u2019en donne peut-\u00eatre pas \u00e0 vos coll\u00e8gues non plus. Vous pourriez aller lui en parler&nbsp;en groupe.<\/p>\n<p>Selon la <em>Loi sur les normes d\u2019emploi <\/em>de l\u2019Ontario, votre employeur ne peut pas <a href=\"https:\/\/stepstojustice.ca\/fr\/common-question-plus\/employment-and-work\/mon-employeur-peut-il-me-punir-si-j%E2%80%99exerce-mes-droits\">vous punir ou menacer de vous punir<\/a> parce que vous lui avez demand\u00e9 de respecter vos droits.<\/p>\n<p>Si votre employeur vous punit parce que vous avez revendiqu\u00e9 vos droits, vous pourriez \u00eatre en mesure de <a href=\"https:\/\/stepstojustice.ca\/fr\/common-question-plus\/employment-and-work\/comment-puis-je-pr%C3%A9senter-une-r%C3%A9clamation-relative-aux\">d\u00e9poser une r\u00e9clamation au minist\u00e8re du Travail<\/a>.<\/p>\n<p>Cela dit, la plupart des gens ne pr\u00e9sentent pas de r\u00e9clamation contre leur employeur actuel parce que rien dans les <a href=\"https:\/\/stepstojustice.ca\/fr\/common-question-plus\/employment-and-work\/mon-employeur-peut-il-me-punir-si-j%E2%80%99exerce-mes-droits\">lois sur la protection des travailleurs<\/a> n\u2019emp\u00eache un employeur de cong\u00e9dier un travailleur. <a href=\"https:\/\/stepstojustice.ca\/fr\/common-question-plus\/employment-and-work\/j%E2%80%99ai-%C3%A9t%C3%A9-cong%C3%A9di%C3%A9-%C3%A0-combien-de-jours-de-pr%C3%A9avis-ai-je-droit\">Si vous \u00eates cong\u00e9di\u00e9<\/a>, c\u2019est \u00e0 vous qu\u2019il revient de prendre des mesures contre votre employeur pour avoir ce qu\u2019il vous doit.<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses - Steps to justice<\/title>\n<meta name=\"description\" content=\"Parlez-en \u00e0 vos coll\u00e8gues. Si votre employeur ne vous donne pas de pauses, il n\u2019en donne peut-\u00eatre pas \u00e0 vos coll\u00e8gues non plus. Vous pourriez aller lui\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses - Steps to justice\" \/>\n<meta property=\"og:description\" content=\"Parlez-en \u00e0 vos coll\u00e8gues. Si votre employeur ne vous donne pas de pauses, il n\u2019en donne peut-\u00eatre pas \u00e0 vos coll\u00e8gues non plus. Vous pourriez aller lui\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/\" \/>\n<meta property=\"og:site_name\" content=\"Steps to justice\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-30T12:50:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/\",\"url\":\"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/\",\"name\":\"3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses - Steps to justice\",\"isPartOf\":{\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"dateModified\":\"2018-07-30T12:50:49+00:00\",\"description\":\"Parlez-en \u00e0 vos coll\u00e8gues. Si votre employeur ne vous donne pas de pauses, il n\u2019en donne peut-\u00eatre pas \u00e0 vos coll\u00e8gues non plus. Vous pourriez aller lui\",\"breadcrumb\":{\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsite.stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Next steps\",\"item\":\"https:\/\/newsite.stepstojustice.ca\/steps\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/newsite.stepstojustice.ca\/fr\/\",\"name\":\"Steps to justice\",\"description\":\"Step-by-step information about legal problems\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsite.stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses - Steps to justice","description":"Parlez-en \u00e0 vos coll\u00e8gues. Si votre employeur ne vous donne pas de pauses, il n\u2019en donne peut-\u00eatre pas \u00e0 vos coll\u00e8gues non plus. Vous pourriez aller lui","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses - Steps to justice","og_description":"Parlez-en \u00e0 vos coll\u00e8gues. Si votre employeur ne vous donne pas de pauses, il n\u2019en donne peut-\u00eatre pas \u00e0 vos coll\u00e8gues non plus. Vous pourriez aller lui","og_url":"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/","og_site_name":"Steps to justice","article_modified_time":"2018-07-30T12:50:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/","url":"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/","name":"3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses - Steps to justice","isPartOf":{"@id":"https:\/\/newsite.stepstojustice.ca\/fr\/#website"},"datePublished":"-0001-11-30T00:00:00+00:00","dateModified":"2018-07-30T12:50:49+00:00","description":"Parlez-en \u00e0 vos coll\u00e8gues. Si votre employeur ne vous donne pas de pauses, il n\u2019en donne peut-\u00eatre pas \u00e0 vos coll\u00e8gues non plus. Vous pourriez aller lui","breadcrumb":{"@id":"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/steps\/employment-and-work\/3-\u00e9tudiez-les-options-qui-s\u2019offrent-\u00e0-vous-si-vous-n\u2019\u00eates-pas-accord\u00e9-de-pauses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsite.stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Next steps","item":"https:\/\/newsite.stepstojustice.ca\/steps\/"},{"@type":"ListItem","position":3,"name":"3. \u00c9tudiez les options qui s\u2019offrent \u00e0 vous si vous n\u2019\u00eates pas accord\u00e9 de pauses"}]},{"@type":"WebSite","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/#website","url":"https:\/\/newsite.stepstojustice.ca\/fr\/","name":"Steps to justice","description":"Step-by-step information about legal problems","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsite.stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"meta_box":{"questions_to_steps_from":["1171612"]},"_links":{"self":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177319"}],"collection":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps"}],"about":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/steps"}],"author":[{"embeddable":true,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/steps\/1177319\/revisions"}],"wp:attachment":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1177319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}