{"id":1171590,"date":"2017-10-19T13:30:59","date_gmt":"2017-10-19T17:30:59","guid":{"rendered":""},"modified":"2019-04-05T09:56:50","modified_gmt":"2019-04-05T09:56:50","slug":"mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires","status":"publish","type":"questions","link":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/","title":{"rendered":"Mon employeur doit-il me payer mes heures suppl\u00e9mentaires?"},"content":{"rendered":"<p>La <em>Loi sur les normes d\u2019emploi<\/em> contient les normes minimales que doivent respecter les employeurs. Ces normes concernent entre autres le paiement des heures suppl\u00e9mentaires.<\/p>\n<p>La plupart du temps, si vous travaillez plus de <a href=\"https:\/\/stepstojustice.ca\/fr\/common-question-plus\/employment-and-work\/est-ce-que-les-lois-ontariennes-sur-la-r%C3%A9mun%C3%A9ration-s\">44&nbsp;heures au cours d\u2019une m\u00eame semaine<\/a>, les heures travaill\u00e9es en plus de ces 44 sont consid\u00e9r\u00e9es comme \u00e9tant suppl\u00e9mentaires.<\/p>\n<p>Vous gagnez alors une fois et demie votre salaire horaire pour chaque heure suppl\u00e9mentaire travaill\u00e9e. Par exemple, si vous gagnez normalement <strong>16&nbsp;$<\/strong> de l\u2019heure, votre taux pour les heures suppl\u00e9mentaires est de <strong>24&nbsp;$<\/strong> de l\u2019heure.<\/p>\n<p>Ces r\u00e8gles de la <em>Loi sur les normes d\u2019emploi <\/em>concernant les heures suppl\u00e9mentaires ne s\u2019appliquent <strong>pas <\/strong>si vous acceptez d\u2019<a href=\"https:\/\/stepstojustice.ca\/fr\/common-question-plus\/employment-and-work\/un-employeur-peut-il-me-demander-de-signer-une-entente-sur\">autres r\u00e8gles<\/a> par \u00e9crit.<\/p>\n<h3>R\u00e8gles que vous pouvez accepter<\/h3>\n<p>Vous pouvez accepter&nbsp;:<\/p>\n<ul>\n<li>que les heures suppl\u00e9mentaires vous soient rendues en cong\u00e9s pay\u00e9s plut\u00f4t qu\u2019en argent;<\/li>\n<li>que vos heures suppl\u00e9mentaires soient calcul\u00e9es sur une moyenne, c\u2019est-\u00e0-dire en fonction de la moyenne des heures suppl\u00e9mentaires travaill\u00e9es sur une p\u00e9riode de 2 semaines ou plus, jusqu&rsquo;\u00e0 4 semaines maximum, et non du nombre r\u00e9el d\u2019heures suppl\u00e9mentaires&nbsp;pour chaque semaine.<\/li>\n<\/ul>\n<p>Les syndicats peuvent aussi conclure des ententes de calcul de la moyenne qui s\u2019appliquent aux travailleurs.<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","legal-topic":[42145,42213,42215],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mon employeur doit-il me payer mes heures suppl\u00e9mentaires? - Steps to justice<\/title>\n<meta name=\"description\" content=\"La Loi sur les normes d\u2019emploi contient les normes minimales que doivent respecter les employeurs. Ces normes concernent entre autres le paiement des\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mon employeur doit-il me payer mes heures suppl\u00e9mentaires? - Steps to justice\" \/>\n<meta property=\"og:description\" content=\"La Loi sur les normes d\u2019emploi contient les normes minimales que doivent respecter les employeurs. Ces normes concernent entre autres le paiement des\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Steps to justice\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-05T09:56:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/\",\"url\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/\",\"name\":\"Mon employeur doit-il me payer mes heures suppl\u00e9mentaires? - Steps to justice\",\"isPartOf\":{\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"dateModified\":\"2019-04-05T09:56:50+00:00\",\"description\":\"La Loi sur les normes d\u2019emploi contient les normes minimales que doivent respecter les employeurs. Ces normes concernent entre autres le paiement des\",\"breadcrumb\":{\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsite.stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions\",\"item\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mon employeur doit-il me payer mes heures suppl\u00e9mentaires?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/newsite.stepstojustice.ca\/fr\/\",\"name\":\"Steps to justice\",\"description\":\"Step-by-step information about legal problems\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsite.stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mon employeur doit-il me payer mes heures suppl\u00e9mentaires? - Steps to justice","description":"La Loi sur les normes d\u2019emploi contient les normes minimales que doivent respecter les employeurs. Ces normes concernent entre autres le paiement des","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Mon employeur doit-il me payer mes heures suppl\u00e9mentaires? - Steps to justice","og_description":"La Loi sur les normes d\u2019emploi contient les normes minimales que doivent respecter les employeurs. Ces normes concernent entre autres le paiement des","og_url":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/","og_site_name":"Steps to justice","article_modified_time":"2019-04-05T09:56:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/","url":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/","name":"Mon employeur doit-il me payer mes heures suppl\u00e9mentaires? - Steps to justice","isPartOf":{"@id":"https:\/\/newsite.stepstojustice.ca\/fr\/#website"},"datePublished":"-0001-11-30T00:00:00+00:00","dateModified":"2019-04-05T09:56:50+00:00","description":"La Loi sur les normes d\u2019emploi contient les normes minimales que doivent respecter les employeurs. Ces normes concernent entre autres le paiement des","breadcrumb":{"@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/employment-and-work\/mon-employeur-doit-il-me-payer-mes-heures-suppl\u00e9mentaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsite.stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions","item":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/"},{"@type":"ListItem","position":3,"name":"Mon employeur doit-il me payer mes heures suppl\u00e9mentaires?"}]},{"@type":"WebSite","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/#website","url":"https:\/\/newsite.stepstojustice.ca\/fr\/","name":"Steps to justice","description":"Step-by-step information about legal problems","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsite.stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"meta_box":{"date_fg19r358tw7":"2019-04-04 00:00:00","date_sgrhr9fx3j":"2018-10-19 00:00:00","text_qgvph2rt54":"","text_mb2unyqw82h":"","text_z4722ywvha":"","textarea_i237k2mg4u":"Jan 2018: changes to WAC resources; changed example wage figures to match the English page.","date_mvzg7sr921":"","textarea_0ej69ng0xn48":"","file_1s3spou4tld":[],"text_0iky8vwgh18v":"marianne.stephens","date_e0vrot0tvds":"2017-10-19 13:30:59 -0400","text_y2tadrpr98":"added primary topic field","number_98lw0j89q05":"1465","post_0glwwksj820p":[1171585,1171601,1171553],"questions_to_resources_to":["1186697","1186599","1186588","1186585","1181556"],"questions_to_guided_pathways_to":[],"questions_to_alerts_to":[],"questions_to_steps_to":["1177432","1177433","1177434"]},"_links":{"self":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171590"}],"collection":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/questions"}],"author":[{"embeddable":true,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171590\/revisions"}],"wp:attachment":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1171590"}],"wp:term":[{"taxonomy":"legal-topic","embeddable":true,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/legal-topic?post=1171590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}