{"id":1171143,"date":"2020-02-20T09:42:49","date_gmt":"2020-02-20T14:42:49","guid":{"rendered":""},"modified":"2021-01-29T11:13:25","modified_gmt":"2021-01-29T11:13:25","slug":"je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente","status":"publish","type":"questions","link":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/","title":{"rendered":"Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d&rsquo;ordre humanitaire?"},"content":{"rendered":"<p>Vous pourriez avoir le droit de pr\u00e9senter une demande de r\u00e9sidence permanente pour consid\u00e9rations d&rsquo;ordre humanitaire (CH) \u00e0 <a class=\"links-link ext\" href=\"\/fr\/links\/immigration-r%C3%A9fugi%C3%A9s-et-citoyennet%C3%A9-canadalink-external\" target=\"_blank\">Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada<\/a> (IRCC).<\/p>\n<p>En r\u00e8gle g\u00e9n\u00e9rale, il faut \u00eatre <strong>\u00e0 l&rsquo;ext\u00e9rieur<\/strong> du Canada pour pouvoir pr\u00e9senter une demande de r\u00e9sidence permanente. Il y a toutefois des situations o\u00f9 vous pouvez demander \u00e0 IRCC de faire exception \u00e0 la r\u00e8gle.<\/p>\n<p>La demande pour CH a pour but d&rsquo;obtenir d&rsquo;IRCC la permission de demander la r\u00e9sidence permanente \u00e0 l&rsquo;int\u00e9rieur du Canada pour des consid\u00e9rations d&rsquo;ordre humanitaire.<\/p>\n<p>Vous avez habituellement le droit de pr\u00e9senter une demande pour CH au Canada, sauf dans certains cas.<\/p>\n<h3>Les consid\u00e9rations d&rsquo;ordre humanitaire<\/h3>\n<p>Une consid\u00e9ration d&rsquo;ordre humanitaire peut \u00eatre presque n&rsquo;importe quel fait qui cr\u00e9era chez les autres un sentiment de compassion et un d\u00e9sir de vous venir en aide. Par exemple, IRCC peut tenir compte <a href=\"\/fr\/questions\/immigration\/je-veux-pr\u00e9senter-une-demande-de-r\u00e9sidence-permanente-pour-consid\u00e9rations-fournir\">du temps que vous avez pass\u00e9 au Canada, des probl\u00e8mes de sant\u00e9 que vous avez et des difficult\u00e9s que vous pourriez vivre si vous \u00eates renvoy\u00e9 du pays<\/a>. IRCC ne peut traiter les risques de votre demande pour CH de la m\u00eame fa\u00e7on que la Commission de l&rsquo;immigration et du statut de r\u00e9fugi\u00e9 le ferait pour une <a href=\"\/fr\/steps\/refugee-law\/1-renseignez-vous-sur-les-personnes-autoris%C3%A9es-%C3%A0-demander-l%E2%80%99asile-au-canada\">demande d&rsquo;asile<\/a>. Par contre, une situation qui met un demandeur d&rsquo;asile en danger pourrait aussi \u00eatre une bonne consid\u00e9ration d&rsquo;ordre humanitaire pour votre demande.<\/p>\n<p>Parmi les facteurs importants, il y a l&rsquo;existence d&rsquo;un enfant qui serait directement touch\u00e9 par la d\u00e9cision si l&rsquo;on vous for\u00e7ait \u00e0 quitter le Canada. IRCC doit tenir compte de l&rsquo;<a class=\"links-link ext\" href=\"\/fr\/links\/%C3%A9valuation-des-consid%C3%A9rations-dordre-humanitaire-int%C3%A9r%C3%AAt-sup%C3%A9rieur-de-lenfant\" target=\"_blank\">int\u00e9r\u00eat sup\u00e9rieur de cet enfant<\/a>.<\/p>\n<p>Le fait de pr\u00e9senter une demande pour CH ne vous donne pas le droit de rester au Canada jusqu&rsquo;\u00e0 ce qu&rsquo;elle soit trait\u00e9e. Pour savoir si vous risquez d&rsquo;\u00eatre renvoy\u00e9 du pays, il est important de <a href=\"\/fr\/questions\/immigration\/o%C3%B9-puis-je-obtenir-un-conseil-et-de-lassistance-juridiques-pour-un-probl%C3%A8me\">demander des conseils juridiques<\/a>.<\/p>\n<h3>Pr\u00e9senter des consid\u00e9rations d&rsquo;ordre humanitaire dans d&rsquo;autres types de demandes<\/h3>\n<p>Vous pouvez aussi pr\u00e9senter vos consid\u00e9rations d&rsquo;ordre humanitaires \u00e0 IRCC dans d&rsquo;autres types de demandes. C&rsquo;est le cas par exemple si vous souhaitez parrainer votre \u00e9poux, conjoint de fait ou partenaire dans sa demande de r\u00e9sidence permanente, mais que ce dernier ne peut pas s\u00e9journer au pays en raison des crimes qu&rsquo;il a commis.<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","legal-topic":[42150,42414,42415],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d&#039;ordre humanitaire? - Steps to justice<\/title>\n<meta name=\"description\" content=\"Vous pourriez avoir le droit de pr\u00e9senter une demande de r\u00e9sidence permanente pour consid\u00e9rations d&#039;ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d&#039;ordre humanitaire? - Steps to justice\" \/>\n<meta property=\"og:description\" content=\"Vous pourriez avoir le droit de pr\u00e9senter une demande de r\u00e9sidence permanente pour consid\u00e9rations d&#039;ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/\" \/>\n<meta property=\"og:site_name\" content=\"Steps to justice\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-29T11:13:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/\",\"url\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/\",\"name\":\"Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d'ordre humanitaire? - Steps to justice\",\"isPartOf\":{\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"dateModified\":\"2021-01-29T11:13:25+00:00\",\"description\":\"Vous pourriez avoir le droit de pr\u00e9senter une demande de r\u00e9sidence permanente pour consid\u00e9rations d'ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et\",\"breadcrumb\":{\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsite.stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions\",\"item\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d&rsquo;ordre humanitaire?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/newsite.stepstojustice.ca\/fr\/\",\"name\":\"Steps to justice\",\"description\":\"Step-by-step information about legal problems\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsite.stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d'ordre humanitaire? - Steps to justice","description":"Vous pourriez avoir le droit de pr\u00e9senter une demande de r\u00e9sidence permanente pour consid\u00e9rations d'ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d'ordre humanitaire? - Steps to justice","og_description":"Vous pourriez avoir le droit de pr\u00e9senter une demande de r\u00e9sidence permanente pour consid\u00e9rations d'ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et","og_url":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/","og_site_name":"Steps to justice","article_modified_time":"2021-01-29T11:13:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/","url":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/","name":"Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d'ordre humanitaire? - Steps to justice","isPartOf":{"@id":"https:\/\/newsite.stepstojustice.ca\/fr\/#website"},"datePublished":"-0001-11-30T00:00:00+00:00","dateModified":"2021-01-29T11:13:25+00:00","description":"Vous pourriez avoir le droit de pr\u00e9senter une demande de r\u00e9sidence permanente pour consid\u00e9rations d'ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et","breadcrumb":{"@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsite.stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions","item":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/"},{"@type":"ListItem","position":3,"name":"Je suis actuellement au Canada. Puis-je demander la r\u00e9sidence permanente pour consid\u00e9rations d&rsquo;ordre humanitaire?"}]},{"@type":"WebSite","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/#website","url":"https:\/\/newsite.stepstojustice.ca\/fr\/","name":"Steps to justice","description":"Step-by-step information about legal problems","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsite.stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"meta_box":{"date_fg19r358tw7":"2019-11-21 00:00:00","date_sgrhr9fx3j":"2020-11-21 00:00:00","text_qgvph2rt54":"","text_mb2unyqw82h":"Caroline Lindberg","text_z4722ywvha":"Kim McCutcheon","textarea_i237k2mg4u":"Nir Gepner, Willowdale CLS","date_mvzg7sr921":"","textarea_0ej69ng0xn48":"","file_1s3spou4tld":[{"icon":"<img width=\"48\" height=\"64\" src=\"https:\/\/newsite.stepstojustice.ca\/wp-includes\/images\/media\/document.png\" alt=\"\">","name":"2019-Dec-13_I\u2019m in Canada. Can I apply to stay permanently on H&C grounds.docx","path":"\/home\/news2jdev\/public_html\/home\/news2jdev\/system\/files\/2019-Dec-13_I\u2019m in Canada. Can I apply to stay permanently on H&C grounds.docx","url":"https:\/\/newsite.stepstojustice.ca\/system\/files\/2019-Dec-13_I\u2019m in Canada. Can I apply to stay permanently on H&C grounds.docx","title":"2019-Dec-13_I\u2019m in Canada. Can I apply to stay permanently on H&C grounds","edit_link":""}],"text_0iky8vwgh18v":"marianne.stephens","date_e0vrot0tvds":"2020-02-20 09:42:49 -0500","text_y2tadrpr98":"Edited by marie.koona.","number_98lw0j89q05":"985","post_0glwwksj820p":[1171833,1171141,1171139],"questions_to_resources_to":["1196997","1185976","1185977","1187345","1181954"],"questions_to_guided_pathways_to":[],"questions_to_alerts_to":[],"questions_to_steps_to":["1175974","1175973","1175972"]},"_links":{"self":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171143"}],"collection":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/questions"}],"author":[{"embeddable":true,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171143\/revisions"}],"wp:attachment":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1171143"}],"wp:term":[{"taxonomy":"legal-topic","embeddable":true,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/legal-topic?post=1171143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}