{"id":1171141,"date":"2020-02-19T13:32:38","date_gmt":"2020-02-19T18:32:38","guid":{"rendered":""},"modified":"2020-02-24T12:24:59","modified_gmt":"2020-02-24T12:24:59","slug":"je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence","status":"publish","type":"questions","link":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/","title":{"rendered":"Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d&rsquo;ordre humanitaire?"},"content":{"rendered":"<p>Il faut pr\u00e9senter une demande pour consid\u00e9rations d&rsquo;ordre humanitaire (CH) \u00e0 <a class=\"links-link ext\" href=\"\/fr\/links\/immigration-r%C3%A9fugi%C3%A9s-et-citoyennet%C3%A9-canadalink-external\" target=\"_blank\">Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada<\/a> (IRCC).<\/p>\n<p>Certaines personnes <a href=\"\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-puis-je-demander-la-r\u00e9sidence-permanente\">ne peuvent pas pr\u00e9senter ce type de demande<\/a>.<\/p>\n<p>En r\u00e8gle g\u00e9n\u00e9rale, il faut \u00eatre <strong>\u00e0 l&rsquo;ext\u00e9rieur<\/strong> du Canada pour pouvoir pr\u00e9senter une demande de r\u00e9sidence permanente. Il y a toutefois des situations o\u00f9 vous pouvez demander \u00e0 IRCC de faire exception \u00e0 la r\u00e8gle.<\/p>\n<p>La demande pour CH a pour but d&rsquo;obtenir d&rsquo;IRCC la permission de demander la r\u00e9sidence permanente \u00e0 l&rsquo;int\u00e9rieur du Canada pour des consid\u00e9rations d&rsquo;ordre humanitaire.<\/p>\n<h3>Pr\u00e9senter des consid\u00e9rations d&rsquo;ordre humanitaire dans d&rsquo;autres types de demandes<\/h3>\n<p>Vous pouvez aussi pr\u00e9senter vos consid\u00e9rations d&rsquo;ordre humanitaire \u00e0 IRCC dans d&rsquo;autres types de demandes. C&rsquo;est le cas par exemple si votre \u00e9poux ou partenaire veut vous parrainer dans votre demande de r\u00e9sidence permanente, mais que vous ne pouvez pas entrer au pays en raison des crimes que vous avez commis.<\/p>\n<h3>Les deux \u00e9tapes d&rsquo;approbation de votre demande<\/h3>\n<p>Votre demande de r\u00e9sidence permanente pour CH passe par 2&nbsp;\u00e9tapes. Pour qu&rsquo;elle soit accept\u00e9e, IRCC doit d\u00e9cider&nbsp;:<\/p>\n<ol>\n<li>de vous laisser demander la r\u00e9sidence permanente au Canada pour des consid\u00e9rations d&rsquo;ordre humanitaire; et<\/li>\n<li>de vous approuver pour le statut de r\u00e9sident permanent au Canada.<\/li>\n<\/ol>\n<h3>La fa\u00e7on dont votre demande sera \u00e9tudi\u00e9e<\/h3>\n<p>Le pouvoir d&rsquo;accepter ou non une demande pour CH est \u00ab&nbsp;discr\u00e9tionnaire&nbsp;\u00bb. Cela signifie que l&rsquo;agent d&rsquo;immigration a une grande libert\u00e9 dans sa d\u00e9cision de l&rsquo;accepter ou non.<\/p>\n<p>Cela dit, sa d\u00e9cision doit \u00eatre fond\u00e9e sur des preuves. Et ces preuves, il doit <strong>toutes <\/strong>les consid\u00e9rer<strong> dans leur ensemble<\/strong> pour d\u00e9terminer si la demande est solidement appuy\u00e9e. Autrement dit, l&rsquo;agent ne peut \u00e9tudier les preuves s\u00e9par\u00e9ment; il doit les consid\u00e9rer globalement.<\/p>\n<p>Comme vous n&rsquo;aurez pas d&rsquo;audience, et vous ne devriez pas non plus vous faire interroger, c&rsquo;est pourquoi il est important&nbsp;:<\/p>\n<ul>\n<li>d&rsquo;expliquer chacune des raisons pour lesquelles on devrait vous laisser rester au Canada;<\/li>\n<li>d&rsquo;accompagner votre demande des meilleures preuves possible.<\/li>\n<\/ul>\n<p>Si votre demande comporte des erreurs ou qu&rsquo;elle ne contient pas de preuves solides, IRCC pourrait la refuser.<\/p>\n<h3>Les consid\u00e9rations d&rsquo;ordre humanitaire<\/h3>\n<p>Une consid\u00e9ration d&rsquo;ordre humanitaire peut \u00eatre presque n&rsquo;importe quel fait qui cr\u00e9era chez les autres un sentiment de compassion et un d\u00e9sir de vous venir en aide. Par exemple, IRCC peut tenir compte <a href=\"\/fr\/questions\/immigration\/je-veux-pr\u00e9senter-une-demande-de-r\u00e9sidence-permanente-pour-consid\u00e9rations-fournir\">du temps que vous avez pass\u00e9 au Canada, des probl\u00e8mes de sant\u00e9 que vous avez et des difficult\u00e9s que vous pourriez vivre si vous \u00eates renvoy\u00e9 du pays<\/a>. IRCC ne peut traiter les risques de votre demande pour CH de la m\u00eame fa\u00e7on que la Commission de l&rsquo;immigration et du statut de r\u00e9fugi\u00e9 le ferait pour une <a href=\"\/fr\/steps\/refugee-law\/1-renseignez-vous-sur-les-personnes-autoris%C3%A9es-%C3%A0-demander-l%E2%80%99asile-au-canada\">demande d&rsquo;asile<\/a>. Par contre, une situation qui met un demandeur d&rsquo;asile en danger pourrait aussi \u00eatre une bonne consid\u00e9ration d&rsquo;ordre humanitaire pour votre demande.<\/p>\n<p>Parmi les facteurs importants, il y a l&rsquo;existence d&rsquo;un enfant qui serait directement touch\u00e9 par la d\u00e9cision si l&rsquo;on vous for\u00e7ait \u00e0 quitter le Canada. IRCC <strong>doit <\/strong>tenir compte de l&rsquo;<a class=\"links-link ext\" href=\"\/fr\/links\/int%C3%A9r%C3%AAt-sup%C3%A9rieur-de-l%E2%80%99enfant\" target=\"_blank\">int\u00e9r\u00eat sup\u00e9rieur de cet enfant<\/a>.<\/p>\n<h3>Demandez des conseils juridiques<\/h3>\n<p><a href=\"\/fr\/questions\/immigration\/o%C3%B9-puis-je-obtenir-un-conseil-et-de-lassistance-juridiques-pour-un-probl%C3%A8me\">Demandez des conseils juridiques<\/a> avant de pr\u00e9senter une demande pour CH. Vous verrez \u00e0 l&rsquo;\u00e9tape&nbsp;3 pourquoi c&rsquo;est important de le faire.<\/p>\n","protected":false},"author":3,"featured_media":0,"template":"","legal-topic":[42150,42414,42415],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d&#039;ordre humanitaire? - Steps to justice<\/title>\n<meta name=\"description\" content=\"Il faut pr\u00e9senter une demande pour consid\u00e9rations d&#039;ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC). Certaines personnes ne\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d&#039;ordre humanitaire? - Steps to justice\" \/>\n<meta property=\"og:description\" content=\"Il faut pr\u00e9senter une demande pour consid\u00e9rations d&#039;ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC). Certaines personnes ne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/\" \/>\n<meta property=\"og:site_name\" content=\"Steps to justice\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-24T12:24:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/\",\"url\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/\",\"name\":\"Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d'ordre humanitaire? - Steps to justice\",\"isPartOf\":{\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/#website\"},\"datePublished\":\"-0001-11-30T00:00:00+00:00\",\"dateModified\":\"2020-02-24T12:24:59+00:00\",\"description\":\"Il faut pr\u00e9senter une demande pour consid\u00e9rations d'ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC). Certaines personnes ne\",\"breadcrumb\":{\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newsite.stepstojustice.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Questions\",\"item\":\"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d&rsquo;ordre humanitaire?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newsite.stepstojustice.ca\/fr\/#website\",\"url\":\"https:\/\/newsite.stepstojustice.ca\/fr\/\",\"name\":\"Steps to justice\",\"description\":\"Step-by-step information about legal problems\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newsite.stepstojustice.ca\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d'ordre humanitaire? - Steps to justice","description":"Il faut pr\u00e9senter une demande pour consid\u00e9rations d'ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC). Certaines personnes ne","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d'ordre humanitaire? - Steps to justice","og_description":"Il faut pr\u00e9senter une demande pour consid\u00e9rations d'ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC). Certaines personnes ne","og_url":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/","og_site_name":"Steps to justice","article_modified_time":"2020-02-24T12:24:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/","url":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/","name":"Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d'ordre humanitaire? - Steps to justice","isPartOf":{"@id":"https:\/\/newsite.stepstojustice.ca\/fr\/#website"},"datePublished":"-0001-11-30T00:00:00+00:00","dateModified":"2020-02-24T12:24:59+00:00","description":"Il faut pr\u00e9senter une demande pour consid\u00e9rations d'ordre humanitaire (CH) \u00e0 Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada (IRCC). Certaines personnes ne","breadcrumb":{"@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/immigration\/je-suis-actuellement-au-canada-comment-faire-pour-demander-la-r\u00e9sidence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newsite.stepstojustice.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Questions","item":"https:\/\/newsite.stepstojustice.ca\/fr\/questions\/"},{"@type":"ListItem","position":3,"name":"Je suis actuellement au Canada. Comment faire pour demander la r\u00e9sidence permanente pour des consid\u00e9rations d&rsquo;ordre humanitaire?"}]},{"@type":"WebSite","@id":"https:\/\/newsite.stepstojustice.ca\/fr\/#website","url":"https:\/\/newsite.stepstojustice.ca\/fr\/","name":"Steps to justice","description":"Step-by-step information about legal problems","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newsite.stepstojustice.ca\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"meta_box":{"date_fg19r358tw7":"2019-11-21 00:00:00","date_sgrhr9fx3j":"2020-12-10 00:00:00","text_qgvph2rt54":"","text_mb2unyqw82h":"Caroline Lindberg","text_z4722ywvha":"Kim McCutcheon","textarea_i237k2mg4u":"Nir Gepner, Willowdale CLS","date_mvzg7sr921":"","textarea_0ej69ng0xn48":"","file_1s3spou4tld":[{"icon":"<img width=\"48\" height=\"64\" src=\"https:\/\/newsite.stepstojustice.ca\/wp-includes\/images\/media\/document.png\" alt=\"\">","name":"2019-Dec-13_I\u2019m in Canada. How do I apply to stay permanently on H&C grounds.docx","path":"\/home\/news2jdev\/public_html\/home\/news2jdev\/system\/files\/2019-Dec-13_I\u2019m in Canada. How do I apply to stay permanently on H&C grounds.docx","url":"https:\/\/newsite.stepstojustice.ca\/system\/files\/2019-Dec-13_I\u2019m in Canada. How do I apply to stay permanently on H&C grounds.docx","title":"2019-Dec-13_I\u2019m in Canada. How do I apply to stay permanently on H&C grounds","edit_link":""}],"text_0iky8vwgh18v":"marianne.stephens","date_e0vrot0tvds":"2020-02-19 13:32:38 -0500","text_y2tadrpr98":"Edited by marie.koona.","number_98lw0j89q05":"534","post_0glwwksj820p":[1171833,1171139,1171140],"questions_to_resources_to":["1196997","1187345","1181954"],"questions_to_guided_pathways_to":[],"questions_to_alerts_to":[],"questions_to_steps_to":["1175998","1175981","1175980","1175979"]},"_links":{"self":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171141"}],"collection":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions"}],"about":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/types\/questions"}],"author":[{"embeddable":true,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/questions\/1171141\/revisions"}],"wp:attachment":[{"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/media?parent=1171141"}],"wp:term":[{"taxonomy":"legal-topic","embeddable":true,"href":"https:\/\/newsite.stepstojustice.ca\/fr\/wp-json\/wp\/v2\/legal-topic?post=1171141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}